{"id":476,"date":"2020-11-16T14:25:55","date_gmt":"2020-11-16T13:25:55","guid":{"rendered":"https:\/\/www.neuman-avocat.fr\/publications\/?p=476"},"modified":"2021-03-03T21:48:06","modified_gmt":"2021-03-03T20:48:06","slug":"hiver-2020-les-loyers-commerciaux-reconfines","status":"publish","type":"post","link":"https:\/\/www.neuman-avocat.fr\/publications\/hiver-2020-les-loyers-commerciaux-reconfines\/","title":{"rendered":"Hiver 2020-21 : les loyers commerciaux reconfin\u00e9s ?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">(Mis \u00e0 jour du 3 janvier 2021)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La <a rel=\"noreferrer noopener\" href=\"https:\/\/www.legifrance.gouv.fr\/jorf\/id\/JORFTEXT000042520662\" target=\"_blank\">loi n\u00b02020-1379 relative \u00e0 la prorogation de l&rsquo;\u00e9tat d&rsquo;urgence sanitaire<\/a> a \u00e9t\u00e9 promulgu\u00e9e le 15 novembre 2020.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Son article 14 \u00e9voque notamment le sort des loyers et charges locatives commerciaux, <a href=\"https:\/\/www.neuman-avocat.fr\/publications\/coronavirus-covid-19-qui-peut-suspendre-ses-loyers-commerciaux\/\" target=\"_blank\" rel=\"noreferrer noopener\">qui avaient d\u00e9j\u00e0 fait l&rsquo;objet d&rsquo;un traitement sp\u00e9cifique lors du premier confinement<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cet article pr\u00e9voit qu&rsquo;\u00e0 compter du 17 octobre 2020 et jusqu&rsquo;\u00e0 l&rsquo;issue d&rsquo;un d\u00e9lai de deux mois suivant la fin des mesures de fermetures administratives des ERP (\u00e9tablissements recevant du public) dues \u00e0 l&rsquo;\u00e9pid\u00e9mie de Covid 19, <strong>sous certaines conditions d&rsquo;\u00e9ligibilit\u00e9<\/strong>, aucuns int\u00e9r\u00eats, p\u00e9nalit\u00e9s financi\u00e8res ou mesures financi\u00e8res ne sauraient sanctionner le non-paiement des loyers commerciaux \/ professionnels et des charges locatives dus pour la p\u00e9riode au cours de laquelle l&rsquo;activit\u00e9 concern\u00e9e est affect\u00e9e par une mesure de fermeture administrative.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les int\u00e9r\u00eats de retard et p\u00e9nalit\u00e9s ne pourront \u00eatre exig\u00e9s et calcul\u00e9s qu&rsquo;\u00e0 compter de l&rsquo;issue de ce d\u00e9lai de deux mois.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De m\u00eame et pendant cette p\u00e9riode, aucune action, sanction ou voie d&rsquo;ex\u00e9cution forc\u00e9e ne pourra \u00eatre mise en \u0153uvre par le bailleur pour recouvrer sa dette. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le bailleur ne pourra pas non plus faire jouer les s\u00fbret\u00e9s r\u00e9elles (nantissement sur fonds de commerce, par exemple) ou personnelles (caution, par exemple) qui lui auraient \u00e9t\u00e9 conc\u00e9d\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il ne pourra pas lancer de mesure conservatoire aux fins de recouvrement des impay\u00e9s(saisie de compte bancaire \u00e0 titre conservatoire, par exemple).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La compensation reste toutefois possible, ce qui signifie que le bailleur disposant d&rsquo;un d\u00e9p\u00f4t de garantie pourra s&rsquo;en servir comme valeur de paiement des loyers et\/ou charges non r\u00e9gl\u00e9s. Il reviendra par la suite au preneur de reconstituer ledit d\u00e9p\u00f4t de garantie, selon les modalit\u00e9s pr\u00e9vues au contrat de bail.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Egalement, il est pr\u00e9vu que toute proc\u00e9dure d&rsquo;ex\u00e9cution d\u00e9j\u00e0 en cours est suspendue : on parle ici de proc\u00e9dures aff\u00e9rentes aux loyers et charges dus ant\u00e9rieurement au 17 octobre 2020.<br><br>Les crit\u00e8res d&rsquo;\u00e9ligibilit\u00e9 \u00e0 ces mesures ont \u00e9t\u00e9 fix\u00e9s par le <a href=\"https:\/\/www.legifrance.gouv.fr\/jorf\/id\/JORFTEXT000042838319\" target=\"_blank\" rel=\"noreferrer noopener\">d\u00e9cret  n\u00b0 2020-1766 du 30 d\u00e9cembre 2020<\/a> : <br><br>&#8211; deux crit\u00e8res, appr\u00e9ci\u00e9s au jour o\u00f9 l&rsquo;entreprise est affect\u00e9e par une mesure de police administrative, sont communs \u00e0 toutes les situations : <br><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>l&rsquo;effectif salari\u00e9 de l&rsquo;entreprise concern\u00e9e doit \u00eatre inf\u00e9rieur \u00e0 250 salari\u00e9s ;<\/li><li>Le montant de son chiffre d&rsquo;affaires constat\u00e9 lors du dernier exercice clos doit \u00eatre inf\u00e9rieur \u00e0 50 millions d&rsquo;euros ou, pour les activit\u00e9s n&rsquo;ayant pas d&rsquo;exercice clos, le montant de leur chiffre d&rsquo;affaires mensuel moyen est inf\u00e9rieur \u00e0 4,17 millions d&rsquo;euros.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211; un crit\u00e8re compl\u00e9mentaire est aff\u00e9rent \u00e0 la perte de chiffre d&rsquo;affaires subie du fait de la mesure touchant l&rsquo;entreprise concern\u00e9e :<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A. <\/strong>Si elle a \u00e9t\u00e9 affect\u00e9e par une mesure de police administrative, type fermeture obligatoire, la perte de chiffre d&rsquo;affaires subie sur la p\u00e9riode doit \u00eatre d&rsquo;au moins 50 % durant la p\u00e9riode comprise entre le 1er novembre 2020 et le 30 novembre 2020, laquelle est d\u00e9finie comme la diff\u00e9rence entre, d&rsquo;une part, le chiffre d&rsquo;affaires au cours du mois de novembre 2020 et, d&rsquo;autre part :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>le chiffre d&rsquo;affaires durant la m\u00eame p\u00e9riode de l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente ;<\/li><li>ou, si l&rsquo;entreprise le souhaite, le chiffre d&rsquo;affaires mensuel moyen de l&rsquo;ann\u00e9e 2019 ;<\/li><li>ou, pour les entreprises cr\u00e9\u00e9es entre le 1er juin 2019 et le 31 janvier 2020, le chiffre d&rsquo;affaires mensuel moyen sur la p\u00e9riode comprise entre la date de cr\u00e9ation de l&rsquo;entreprise et le 29 f\u00e9vrier 2020 ;<\/li><li>ou, pour les entreprises cr\u00e9\u00e9es entre le 1er f\u00e9vrier 2020 et le 29 f\u00e9vrier 2020, le chiffre d&rsquo;affaires r\u00e9alis\u00e9 en f\u00e9vrier 2020 et ramen\u00e9 sur un mois ;<\/li><li>ou, pour les entreprises cr\u00e9\u00e9es apr\u00e8s le 1er mars 2020, le chiffre d&rsquo;affaires mensuel moyen r\u00e9alis\u00e9 entre le 1er juillet 2020, ou \u00e0 d\u00e9faut la date de cr\u00e9ation de l&rsquo;entreprise, et le 30 septembre 2020.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>B.<\/strong> Si elle a subi une interdiction d&rsquo;accueil du public (comme pour les restaurants et bars), le chiffre d&rsquo;affaires de novembre mentionn\u00e9 ci-dessus n&rsquo;inclut pas le chiffre d&rsquo;affaires r\u00e9alis\u00e9 sur les activit\u00e9s de vente \u00e0 distance avec retrait en magasin ou livraison.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Afin de justifier de la r\u00e9union de ces crit\u00e8res, il conviendra de produire une d\u00e9claration sur l&rsquo;honneur en ce sens, accompagn\u00e9e de tout document comptable, fiscal ou social en attestant, et, pour la perte de chiffre d&rsquo;affaires, une estimation.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si l&rsquo;entreprise concern\u00e9e a moins de cinquante salari\u00e9s et a sollicit\u00e9 une aide du fonds de solidarit\u00e9, elle peut justifier de sa situation en pr\u00e9sentant l&rsquo;accus\u00e9-r\u00e9ception du d\u00e9p\u00f4t de sa demande d&rsquo;\u00e9ligibilit\u00e9 au titre du mois de novembre 2020, accompagn\u00e9 de tout document comptable ou fiscal permettant de justifier qu&rsquo;elle ne d\u00e9passent pas le niveau de chiffre d&rsquo;affaires susvis\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><!-- wp:paragraph --><\/p>\n<p>Les int\u00e9r\u00eats de retard et p\u00e9nalit\u00e9s ne pourront \u00eatre exig\u00e9s et calcul\u00e9s qu&rsquo;\u00e0 compter de l&rsquo;issue de ce d\u00e9lai de deux mois.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-476","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hiver 2020-21 : les loyers commerciaux reconfin\u00e9s ?<\/title>\n<meta name=\"description\" content=\"Lors du reconfinement de l&#039;hiver 2020-21, quel sort sera r\u00e9serv\u00e9 aux loyers des locaux commerciaux frapp\u00e9s par la femeture obligatoire ?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.neuman-avocat.fr\/publications\/hiver-2020-les-loyers-commerciaux-reconfines\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hiver 2020-21 : les loyers commerciaux reconfin\u00e9s ?\" \/>\n<meta property=\"og:description\" content=\"Lors du reconfinement de l&#039;hiver 2020-21, quel sort sera r\u00e9serv\u00e9 aux loyers des locaux commerciaux frapp\u00e9s par la femeture obligatoire ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.neuman-avocat.fr\/publications\/hiver-2020-les-loyers-commerciaux-reconfines\/\" \/>\n<meta property=\"og:site_name\" content=\"Publications Neuman Avocat\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-16T13:25:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-03T20:48:06+00:00\" \/>\n<meta name=\"author\" content=\"mneuman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"mneuman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.neuman-avocat.fr\\\/publications\\\/hiver-2020-les-loyers-commerciaux-reconfines\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.neuman-avocat.fr\\\/publications\\\/hiver-2020-les-loyers-commerciaux-reconfines\\\/\"},\"author\":{\"name\":\"mneuman\",\"@id\":\"https:\\\/\\\/www.neuman-avocat.fr\\\/publications\\\/#\\\/schema\\\/person\\\/ddcc6d3a53112a8d9182f724eee641b1\"},\"headline\":\"Hiver 2020-21 : les loyers commerciaux reconfin\u00e9s ?\",\"datePublished\":\"2020-11-16T13:25:55+00:00\",\"dateModified\":\"2021-03-03T20:48:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.neuman-avocat.fr\\\/publications\\\/hiver-2020-les-loyers-commerciaux-reconfines\\\/\"},\"wordCount\":865,\"commentCount\":0,\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.neuman-avocat.fr\\\/publications\\\/hiver-2020-les-loyers-commerciaux-reconfines\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.neuman-avocat.fr\\\/publications\\\/hiver-2020-les-loyers-commerciaux-reconfines\\\/\",\"url\":\"https:\\\/\\\/www.neuman-avocat.fr\\\/publications\\\/hiver-2020-les-loyers-commerciaux-reconfines\\\/\",\"name\":\"Hiver 2020-21 : les loyers commerciaux reconfin\u00e9s ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.neuman-avocat.fr\\\/publications\\\/#website\"},\"datePublished\":\"2020-11-16T13:25:55+00:00\",\"dateModified\":\"2021-03-03T20:48:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.neuman-avocat.fr\\\/publications\\\/#\\\/schema\\\/person\\\/ddcc6d3a53112a8d9182f724eee641b1\"},\"description\":\"Lors du reconfinement de l'hiver 2020-21, quel sort sera r\u00e9serv\u00e9 aux loyers des locaux commerciaux frapp\u00e9s par la femeture obligatoire ?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.neuman-avocat.fr\\\/publications\\\/hiver-2020-les-loyers-commerciaux-reconfines\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.neuman-avocat.fr\\\/publications\\\/hiver-2020-les-loyers-commerciaux-reconfines\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.neuman-avocat.fr\\\/publications\\\/hiver-2020-les-loyers-commerciaux-reconfines\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.neuman-avocat.fr\\\/publications\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hiver 2020-21 : les loyers commerciaux reconfin\u00e9s ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.neuman-avocat.fr\\\/publications\\\/#website\",\"url\":\"https:\\\/\\\/www.neuman-avocat.fr\\\/publications\\\/\",\"name\":\"Publications Neuman Avocat\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.neuman-avocat.fr\\\/publications\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.neuman-avocat.fr\\\/publications\\\/#\\\/schema\\\/person\\\/ddcc6d3a53112a8d9182f724eee641b1\",\"name\":\"mneuman\",\"url\":\"https:\\\/\\\/www.neuman-avocat.fr\\\/publications\\\/author\\\/mneuman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hiver 2020-21 : les loyers commerciaux reconfin\u00e9s ?","description":"Lors du reconfinement de l'hiver 2020-21, quel sort sera r\u00e9serv\u00e9 aux loyers des locaux commerciaux frapp\u00e9s par la femeture obligatoire ?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.neuman-avocat.fr\/publications\/hiver-2020-les-loyers-commerciaux-reconfines\/","og_locale":"fr_FR","og_type":"article","og_title":"Hiver 2020-21 : les loyers commerciaux reconfin\u00e9s ?","og_description":"Lors du reconfinement de l'hiver 2020-21, quel sort sera r\u00e9serv\u00e9 aux loyers des locaux commerciaux frapp\u00e9s par la femeture obligatoire ?","og_url":"https:\/\/www.neuman-avocat.fr\/publications\/hiver-2020-les-loyers-commerciaux-reconfines\/","og_site_name":"Publications Neuman Avocat","article_published_time":"2020-11-16T13:25:55+00:00","article_modified_time":"2021-03-03T20:48:06+00:00","author":"mneuman","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"mneuman","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.neuman-avocat.fr\/publications\/hiver-2020-les-loyers-commerciaux-reconfines\/#article","isPartOf":{"@id":"https:\/\/www.neuman-avocat.fr\/publications\/hiver-2020-les-loyers-commerciaux-reconfines\/"},"author":{"name":"mneuman","@id":"https:\/\/www.neuman-avocat.fr\/publications\/#\/schema\/person\/ddcc6d3a53112a8d9182f724eee641b1"},"headline":"Hiver 2020-21 : les loyers commerciaux reconfin\u00e9s ?","datePublished":"2020-11-16T13:25:55+00:00","dateModified":"2021-03-03T20:48:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.neuman-avocat.fr\/publications\/hiver-2020-les-loyers-commerciaux-reconfines\/"},"wordCount":865,"commentCount":0,"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.neuman-avocat.fr\/publications\/hiver-2020-les-loyers-commerciaux-reconfines\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.neuman-avocat.fr\/publications\/hiver-2020-les-loyers-commerciaux-reconfines\/","url":"https:\/\/www.neuman-avocat.fr\/publications\/hiver-2020-les-loyers-commerciaux-reconfines\/","name":"Hiver 2020-21 : les loyers commerciaux reconfin\u00e9s ?","isPartOf":{"@id":"https:\/\/www.neuman-avocat.fr\/publications\/#website"},"datePublished":"2020-11-16T13:25:55+00:00","dateModified":"2021-03-03T20:48:06+00:00","author":{"@id":"https:\/\/www.neuman-avocat.fr\/publications\/#\/schema\/person\/ddcc6d3a53112a8d9182f724eee641b1"},"description":"Lors du reconfinement de l'hiver 2020-21, quel sort sera r\u00e9serv\u00e9 aux loyers des locaux commerciaux frapp\u00e9s par la femeture obligatoire ?","breadcrumb":{"@id":"https:\/\/www.neuman-avocat.fr\/publications\/hiver-2020-les-loyers-commerciaux-reconfines\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.neuman-avocat.fr\/publications\/hiver-2020-les-loyers-commerciaux-reconfines\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.neuman-avocat.fr\/publications\/hiver-2020-les-loyers-commerciaux-reconfines\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.neuman-avocat.fr\/publications\/"},{"@type":"ListItem","position":2,"name":"Hiver 2020-21 : les loyers commerciaux reconfin\u00e9s ?"}]},{"@type":"WebSite","@id":"https:\/\/www.neuman-avocat.fr\/publications\/#website","url":"https:\/\/www.neuman-avocat.fr\/publications\/","name":"Publications Neuman Avocat","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.neuman-avocat.fr\/publications\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.neuman-avocat.fr\/publications\/#\/schema\/person\/ddcc6d3a53112a8d9182f724eee641b1","name":"mneuman","url":"https:\/\/www.neuman-avocat.fr\/publications\/author\/mneuman\/"}]}},"_links":{"self":[{"href":"https:\/\/www.neuman-avocat.fr\/publications\/wp-json\/wp\/v2\/posts\/476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.neuman-avocat.fr\/publications\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.neuman-avocat.fr\/publications\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.neuman-avocat.fr\/publications\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.neuman-avocat.fr\/publications\/wp-json\/wp\/v2\/comments?post=476"}],"version-history":[{"count":0,"href":"https:\/\/www.neuman-avocat.fr\/publications\/wp-json\/wp\/v2\/posts\/476\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.neuman-avocat.fr\/publications\/wp-json\/wp\/v2\/media?parent=476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.neuman-avocat.fr\/publications\/wp-json\/wp\/v2\/categories?post=476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.neuman-avocat.fr\/publications\/wp-json\/wp\/v2\/tags?post=476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}